{"id":42,"count":113,"description":"","link":"https:\/\/citedesrocheuses.com\/en\/evenements\/category\/cinema\/","name":"Movie theater","slug":"cinema","taxonomy":"tribe_events_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/citedesrocheuses.com\/en\/wp-json\/wp\/v2\/tribe_events_cat\/42","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/citedesrocheuses.com\/en\/wp-json\/wp\/v2\/tribe_events_cat"}],"about":[{"href":"https:\/\/citedesrocheuses.com\/en\/wp-json\/wp\/v2\/taxonomies\/tribe_events_cat"}],"wp:post_type":[{"href":"https:\/\/citedesrocheuses.com\/en\/wp-json\/wp\/v2\/tribe_events?tribe_events_cat=42"},{"href":"https:\/\/citedesrocheuses.com\/en\/wp-json\/wp\/v2\/tec_calendar_embed?tribe_events_cat=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}